{"id":233,"count":1,"description":"","link":"https:\/\/boisetame.fr\/en\/tag\/unique-solid-wood-table\/","name":"unique solid wood table","slug":"unique-solid-wood-table","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>unique solid wood table \u0410\u0440\u0445\u0456\u0432\u0438 - boisetame<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boisetame.fr\/en\/tag\/unique-solid-wood-table\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"unique solid wood table \u0410\u0440\u0445\u0456\u0432\u0438 - boisetame\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boisetame.fr\/en\/tag\/unique-solid-wood-table\/\" \/>\n<meta property=\"og:site_name\" content=\"boisetame\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"unique solid wood table \u0410\u0440\u0445\u0456\u0432\u0438 - boisetame","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boisetame.fr\/en\/tag\/unique-solid-wood-table\/","og_locale":"en_US","og_type":"article","og_title":"unique solid wood table \u0410\u0440\u0445\u0456\u0432\u0438 - boisetame","og_url":"https:\/\/boisetame.fr\/en\/tag\/unique-solid-wood-table\/","og_site_name":"boisetame","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/boisetame.fr\/en\/tag\/unique-solid-wood-table\/","url":"https:\/\/boisetame.fr\/en\/tag\/unique-solid-wood-table\/","name":"unique solid wood table \u0410\u0440\u0445\u0456\u0432\u0438 - boisetame","isPartOf":{"@id":"https:\/\/boisetame.fr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/boisetame.fr\/en\/tag\/unique-solid-wood-table\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/boisetame.fr\/en\/tag\/unique-solid-wood-table\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430","item":"https:\/\/boisetame.fr\/en\/"},{"@type":"ListItem","position":2,"name":"unique solid wood table"}]},{"@type":"WebSite","@id":"https:\/\/boisetame.fr\/en\/#website","url":"https:\/\/boisetame.fr\/en\/","name":"boisetame","description":"","publisher":{"@id":"https:\/\/boisetame.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boisetame.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/boisetame.fr\/en\/#organization","name":"boisetame","url":"https:\/\/boisetame.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/boisetame.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/boisetame.fr\/wp-content\/uploads\/2026\/03\/logo-1.svg","contentUrl":"https:\/\/boisetame.fr\/wp-content\/uploads\/2026\/03\/logo-1.svg","width":1280,"height":1280,"caption":"boisetame"},"image":{"@id":"https:\/\/boisetame.fr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/boisetame.fr\/en\/wp-json\/wp\/v2\/tags\/233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boisetame.fr\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/boisetame.fr\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/boisetame.fr\/en\/wp-json\/wp\/v2\/posts?tags=233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}